{"id":5075,"date":"2023-02-16T08:42:34","date_gmt":"2023-02-16T07:42:34","guid":{"rendered":"https:\/\/lucibelleparis.com\/?page_id=5075"},"modified":"2026-06-18T11:58:04","modified_gmt":"2026-06-18T10:58:04","slug":"politique-de-confidentialite","status":"publish","type":"page","link":"https:\/\/lucibelleparis.com\/en\/politique-de-confidentialite\/","title":{"rendered":"Politique de confidentialit\u00e9"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"5075\" class=\"elementor elementor-5075 elementor-3991\" data-elementor-settings=\"{&quot;ha_cmc_init_switcher&quot;:&quot;no&quot;}\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-88cf2ac e-flex e-con-boxed e-con e-parent\" data-id=\"88cf2ac\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8516399 elementor-widget elementor-widget-heading\" data-id=\"8516399\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Politique de confidentialit\u00e9<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e92648e mentions-text elementor-widget elementor-widget-text-editor\" data-id=\"e92648e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Lucibel.le Paris a pour ambition d\u2019\u00eatre une entreprise citoyenne exemplaire et de contribuer \u00e0 la cr\u00e9ation d\u2019un monde \u00e9l\u00e9gant. Nous accordons une grande valeur \u00e0 l\u2019honn\u00eatet\u00e9 et \u00e0 la clart\u00e9 et avons \u00e0 c\u0153ur de construire avec nos clients des relations fortes et durables, fond\u00e9es sur la confiance et l\u2019int\u00e9r\u00eat mutuel. Conform\u00e9ment \u00e0 cette philosophie, la protection de vos donn\u00e9es personnelles est essentielle \u00e0 nos yeux et nous souhaitons vous informer par l\u2019interm\u00e9diaire de la pr\u00e9sente politique de protection des donn\u00e9es personnelles de la mani\u00e8re dont nous collectons et traitons ces donn\u00e9es.<\/p>\n<p>La pr\u00e9sente politique de confidentialit\u00e9 d\u00e9finit et vous informe de la mani\u00e8re dont Lucibel.le paris utilise et prot\u00e8ge les donn\u00e9es \u00e0 caract\u00e8re personnel sur son site accessible \u00e0 partir de l\u2019URL suivante : lucibelleparis.com (ci-apr\u00e8s le \u00ab Site \u00bb).<\/p>\n<p>Veuillez noter que cette politique de confidentialit\u00e9 est susceptible d\u2019\u00eatre modifi\u00e9e ou compl\u00e9t\u00e9e \u00e0 tout moment par Lucibel.le Paris, notamment en vue de se conformer \u00e0 toute \u00e9volution l\u00e9gislative, r\u00e8glementaire, jurisprudentielle ou technologique. Dans un tel cas, la date de sa mise \u00e0 jour sera clairement identifi\u00e9e en t\u00eate de la pr\u00e9sente politique. Ces modifications engagent l\u2019Utilisateur d\u00e8s leur mise en ligne. Il convient par cons\u00e9quent que l\u2019Utilisateur consulte r\u00e9guli\u00e8rement la pr\u00e9sente politique de confidentialit\u00e9 et d\u2019utilisation des cookies afin de prendre connaissance de ses \u00e9ventuelles modifications.<\/p>\n<h2>1. Donn\u00e9es personnelles<\/h2>\n<p>D\u2019une mani\u00e8re g\u00e9n\u00e9rale, il vous est possible de visiter le Site sans communiquer aucune information personnelle vous concernant. En toute hypoth\u00e8se, vous \u00eates en aucune mani\u00e8re oblig\u00e9 de transmettre ces informations \u00e0 Lucibel.le Paris lorsque vous utilisez le Site. N\u00e9anmoins, en cas de refus, il se peut que vous ne puissiez pas b\u00e9n\u00e9ficier de certaines informations ou services que vous avez demand\u00e9.<\/p>\n<p>Lucibel.le Paris peut \u00eatre amen\u00e9 dans certains cas \u00e0 traiter les donn\u00e9es \u00e0 caract\u00e8re personnel list\u00e9es ci-dessous (ci-apr\u00e8s vos \u00ab Informations Personnelles \u00bb) :<\/p>\n<p>pr\u00e9nom et nom de famille ;<br>adresse de courrier \u00e9lectronique ;<br>num\u00e9ro de t\u00e9l\u00e9phone ;<br>adresse postale ;<br>photographie ;<br>toute demande particuli\u00e8re que vous pourriez nous adresser (principalement pour des besoins d\u2019archivage) ;<\/p>\n<p>En fournissant ces informations, vous acceptez express\u00e9ment qu\u2019elles soient trait\u00e9es par Lucibel.le Paris, aux fins indiqu\u00e9es au point 2 ci-dessous ainsi qu\u2019aux fins rappel\u00e9es \u00e0 la fin de chaque formulaire.<\/p>\n<p>Conform\u00e9ment au R\u00e8glement G\u00e9n\u00e9ral sur la Protection des Donn\u00e9es (General Data Protection R\u00e9gulation) adopt\u00e9 par le Parlement europ\u00e9en le 14 avril 2016, et \u00e0 la Loi Informatique et Libert\u00e9s du 6 janvier 1978 modifi\u00e9e, Lucibel.le Paris vous informe des points suivants :<\/p>\n<h3>1.1. Identit\u00e9 du responsable du traitement<\/h3>\n<p>Le responsable du traitement est la soci\u00e9t\u00e9 Lucibel.le Paris.<br>Email : contact@lucibelle.fr<\/p>\n<h3>1.2. Finalit\u00e9s du traitement<\/h3>\n<p>Lucibel.le Paris est susceptible de traiter vos Informations Personnelles :<br>(a) aux fins de vous fournir les informations ou les services que vous avez demand\u00e9 de recevoir (envoi de nos newsletters suite \u00e0 inscription de votre part) ;<br>(b) aux fins de recueillir des informations nous permettant d\u2019am\u00e9liorer notre Site, nos produits et services (notamment par le biais de cookies) ; et\/ou<br>(c) aux fins de pr\u00e9sentation des bienfaits de nos solutions dans l\u2019onglet AVANT\/APRES lorsque vous avez compl\u00e9t\u00e9 une autorisation d&#8217;exploitation \u00e9crite du droit \u00e0 l&#8217;image (traitements ayant pour base l\u00e9gale votre consentement).<\/p>\n<h3>1.3. Base l\u00e9gale<\/h3>\n<p>Nous n\u2019utilisons vos donn\u00e9es personnelles que dans les cas pr\u00e9vus par la r\u00e9glementation en vigueur :<\/p>\n<p>\u2022 l\u2019ex\u00e9cution d\u2019un contrat que nous avons conclu avec vous, et\/ou<br>\u2022 le respect d\u2019une obligation l\u00e9gale, et\/ou<br>\u2022 votre consentement \u00e0 l\u2019utilisation de vos donn\u00e9es, et\/ou<br>\u2022 l\u2019existence d\u2019un int\u00e9r\u00eat l\u00e9gitime \u00e0 utiliser vos donn\u00e9es en veillant \u00e0 ne pas heurter vos droits et int\u00e9r\u00eats, compte tenu de vos attentes raisonnables.<\/p>\n<h3>1.4. Destinataires<\/h3>\n<p>Seul Lucibel.le Paris est destinataire de vos Informations Personnelles. Celles-ci, que ce soit sous forme individuelle ou agr\u00e9g\u00e9e, ne sont jamais transmises \u00e0 un tiers, nonobstant les prestataires auxquels Lucibel.le Paris fait appel (vous trouverez de plus amples informations \u00e0 leur sujet au point 7 ci-dessous). Ni Lucibel.le Paris, ni l\u2019un quelconque de ses prestataires, ne proc\u00e8dent \u00e0 la commercialisation des donn\u00e9es personnelles des visiteurs et Utilisateurs de son Site.<\/p>\n<h3>1.5. Dur\u00e9e de conservation<\/h3>\n<p>Vos Informations Personnelles sont conserv\u00e9es par Lucibel.le Paris uniquement pour le temps correspondant \u00e0 la finalit\u00e9 de la collecte tel qu\u2019indiqu\u00e9 en 2. ci-dessus.<\/p>\n<p>A l\u2019exception des photographies conserv\u00e9es pendant la dur\u00e9e de leur diffusion sur le Site, la dur\u00e9e de traitement de vos donn\u00e9es ne saurait exc\u00e9der 24 mois.<\/p>\n<h3>1.6. Droits Informatique et Libert\u00e9s<\/h3>\n<p>Vous disposez des droits suivants concernant vos Informations Personnelles, que vous pouvez exercer en nous \u00e9crivant \u00e0 l\u2019adresse email (contact@lucibelle.fr), \u00e0 l\u2019adresse postale (cf point 1)<\/p>\n<p>Droit d\u2019acc\u00e8s et de communication des donn\u00e9es<\/p>\n<p>Vous avez la facult\u00e9 d\u2019acc\u00e9der aux Informations Personnelles qui vous concernent. Cependant, en raison de l\u2019obligation de s\u00e9curit\u00e9 et de confidentialit\u00e9 dans le traitement des donn\u00e9es \u00e0 caract\u00e8re personnel qui incombe \u00e0 Lucibel.le Paris, vous \u00eates inform\u00e9 que votre demande sera trait\u00e9e sous r\u00e9serve que vous rapportiez la preuve de votre identit\u00e9, notamment par la production d\u2019un scan de votre titre d\u2019identit\u00e9 valide (en cas de demande par notre formulaire \u00e9lectronique d\u00e9di\u00e9) ou d\u2019une photocopie sign\u00e9e de votre titre d\u2019identit\u00e9 valide (en cas de demande adress\u00e9e par \u00e9crit).<\/p>\n<p>Lucibel.le Paris vous informe qu\u2019il sera en droit, le cas \u00e9ch\u00e9ant, de s\u2019opposer aux demandes manifestement abusives (de par leur nombre, leur caract\u00e8re r\u00e9p\u00e9titif ou syst\u00e9matique). Pour vous aider dans votre d\u00e9marche, notamment si vous d\u00e9sirez exercer votre droit d\u2019acc\u00e8s par le biais d\u2019une demande \u00e9crite \u00e0 l\u2019adresse postale mentionn\u00e9e au point 1, vous trouverez en cliquant sur le lien suivant un mod\u00e8le de courrier \u00e9labor\u00e9 par la Commission Nationale de l\u2019Informatique et des Libert\u00e9s (la \u00ab CNIL \u00bb).<\/p>\n<p>https:\/\/www.cnil.fr\/fr\/modele\/courrier\/exercer-son-droit-dacces<\/p>\n<p>Droit de rectification des donn\u00e9es<\/p>\n<p>Au titre de ce droit, la l\u00e9gislation vous habilite \u00e0 demander la rectification, la mise \u00e0 jour, le verrouillage ou encore l\u2019effacement des donn\u00e9es vous concernant qui peuvent s\u2019av\u00e9rer le cas \u00e9ch\u00e9ant inexactes, erron\u00e9es, incompl\u00e8tes ou obsol\u00e8tes. \u00c9galement, vous pouvez d\u00e9finir des directives g\u00e9n\u00e9rales et particuli\u00e8res relatives au sort des donn\u00e9es \u00e0 caract\u00e8re personnel apr\u00e8s votre d\u00e9c\u00e8s. Le cas \u00e9ch\u00e9ant, les h\u00e9ritiers d\u2019une personne d\u00e9c\u00e9d\u00e9e peuvent exiger de prendre en consid\u00e9ration le d\u00e9c\u00e8s de leur proche et\/ou de proc\u00e9der aux mises \u00e0 jour n\u00e9cessaires. Pour vous aider dans votre d\u00e9marche, notamment si vous d\u00e9sirez exercer, pour votre propre compte ou pour le compte de l\u2019un de vos proches d\u00e9c\u00e9d\u00e9, votre droit de rectification par le biais d\u2019une demande \u00e9crite \u00e0 l\u2019adresse postale mentionn\u00e9e au point 1, vous trouverez en cliquant sur le lien suivant un mod\u00e8le de courrier \u00e9labor\u00e9 par la CNIL.<\/p>\n<p>https:\/\/www.cnil.fr\/fr\/modele\/courrier\/rectifier-des-donnees-inexactes-obsoletes-ou-perimees<\/p>\n<p>Droit d\u2019opposition<\/p>\n<p>L\u2019exercice de ce droit n\u2019est possible que dans l\u2019une des deux situations suivantes : Lorsque l\u2019exercice de ce droit est fond\u00e9 sur des motifs l\u00e9gitimes ; ou Lorsque l\u2019exercice de ce droit vise \u00e0 faire obstacle \u00e0 ce que les donn\u00e9es recueillies soient utilis\u00e9es \u00e0 des fins de prospection commerciale. Pour vous aider dans votre d\u00e9marche, notamment si vous d\u00e9sirez exercer votre droit d\u2019opposition par le biais d\u2019une demande \u00e9crite adress\u00e9e \u00e0 l\u2019adresse postale indiqu\u00e9e au point 1, vous trouverez en cliquant sur le lien suivant un mod\u00e8le de courrier \u00e9labor\u00e9 par la CNIL.<\/p>\n<p>https:\/\/www.cnil.fr\/fr\/modele\/courrier\/supprimer-des-informations-vous-concernant-dun-site-internet<\/p>\n<p>Droit \u00e0 la limitation du traitement<\/p>\n<p>Le droit \u00e0 la limitation de vos donn\u00e9es est un droit qui compl\u00e8te vos autres droits (rectification, opposition\u2026). Si vous contestez l\u2019exactitude des donn\u00e9es utilis\u00e9es par Lucibel.le Paris ou que vous vous opposez \u00e0 ce que vos donn\u00e9es soient trait\u00e9es, la loi autorise Lucibel.le Paris \u00e0 proc\u00e9der \u00e0 une v\u00e9rification ou \u00e0 l\u2019examen de votre demande. Pendant cet examen, vous aurez alors la possibilit\u00e9 de nous demander de geler l\u2019utilisation de vos donn\u00e9es. Concr\u00e8tement, Lucibel.le Paris ne devra plus utiliser les donn\u00e9es mais devra les conserver.<\/p>\n<p>Inversement, vous pouvez demander directement la limitation de certaines donn\u00e9es dans le cas o\u00f9 nous souhaitons les effacer.<\/p>\n<p>Nous mettons cependant \u00e0 votre disposition des outils pour g\u00e9rer vos donn\u00e9es directement sur notre site. Vous les trouverez en bas de page.<\/p>\n<p>Contactez-nous si vous rencontrez des probl\u00e8mes avec leur utilisation.<\/p>\n<h3>1.7. D\u00e9lais de r\u00e9ponse<\/h3>\n<p>Lucibel.le Paris s\u2019engage \u00e0 r\u00e9pondre \u00e0 votre demande d\u2019acc\u00e8s, de rectification ou d\u2019opposition ou toute autre demande compl\u00e9mentaire d\u2019informations dans un d\u00e9lai raisonnable qui ne saurait d\u00e9passer 1 mois \u00e0 compter de la r\u00e9ception de votre demande.<\/p>\n<h3>1.8. Prestataires habilit\u00e9s et transfert vers un pays tiers de l\u2019Union Europ\u00e9enne<\/h3>\n<p>Lucibel.le Paris vous informe qu\u2019il a recours \u00e0 ses prestataires habilit\u00e9s pour faciliter le recueil et le traitement des donn\u00e9es que vous nous avez communiqu\u00e9. Ces prestataires peuvent \u00eatre situ\u00e9s en dehors de l\u2019Union Europ\u00e9enne et ont communication des donn\u00e9es recueillies par le biais des divers formulaires pr\u00e9sents sur le Site (\u00e0 l\u2019exception du formulaire vous permettant d\u2019exercer vos droits Informatique et Libert\u00e9s qui est propos\u00e9 et exploit\u00e9 par Lucibel.le Paris).<\/p>\n<h3>1.9. Plainte aupr\u00e8s de l\u2019autorit\u00e9 comp\u00e9tente<\/h3>\n<p>Si vous consid\u00e9rez que Lucibel.le Paris ne respecte pas ses obligations au regard de vos Informations Personnelles, vous pouvez adresser une plainte ou une demande aupr\u00e8s de l\u2019autorit\u00e9 comp\u00e9tente. En France, l\u2019autorit\u00e9 comp\u00e9tente est la CNIL \u00e0 laquelle vous pouvez adresser une demande par voie \u00e9lectronique en cliquant sur le lien suivant :<\/p>\n<p>https:\/\/www.cnil.fr\/fr\/plaintes\/internet<\/p>\n<h2>2. Politique relative aux cookies<\/h2>\n<p>Lors de votre premi\u00e8re connexion sur le site web de Lucibel.le Paris, vous \u00eates avertis par un bandeau en bas de votre \u00e9cran que des informations relatives \u00e0 votre navigation sont susceptibles d\u2019\u00eatre enregistr\u00e9es dans des fichiers d\u00e9nomm\u00e9s \u00ab cookies \u00bb. Notre politique d\u2019utilisation des cookies vous permet de mieux comprendre les dispositions que nous mettons en \u0153uvre en mati\u00e8re de navigation sur notre site web. Elle vous informe notamment sur l\u2019ensemble des cookies pr\u00e9sents sur notre site web, leur finalit\u00e9 (partie I.) et vous donne la marche \u00e0 suivre pour les param\u00e9trer (partie II.)<\/p>\n<h3>2.1. Informations g\u00e9n\u00e9rales sur les cookies pr\u00e9sents sur le site de Lucibel.le Paris<\/h3>\n<p>Lucibel.le Paris, en tant qu\u2019\u00e9diteur du pr\u00e9sent site web, pourra proc\u00e9der \u00e0 l\u2019implantation d\u2019un cookie sur le disque dur de votre terminal (ordinateur, tablette, mobile etc.) afin de vous garantir une navigation fluide et optimale sur notre site Internet. Les \u00ab cookies \u00bb (ou t\u00e9moins de connexion) sont des petits fichiers texte de taille limit\u00e9e qui nous permettent de reconna\u00eetre votre ordinateur, votre tablette ou votre mobile aux fins de personnaliser les services que nous vous proposons.<br>Les informations recueillies par le biais des cookies ne permettent en aucune mani\u00e8re de vous identifier nominativement. Elles sont utilis\u00e9es exclusivement pour nos besoins propres afin d\u2019am\u00e9liorer l\u2019interactivit\u00e9 et la performance de notre site web et de vous adresser des contenus adapt\u00e9s \u00e0 vos centres d\u2019int\u00e9r\u00eats. Aucune de ces informations ne fait l\u2019objet d\u2019une communication aupr\u00e8s de tiers sauf lorsque Lucibel.le Paris a obtenu au pr\u00e9alable votre consentement ou bien lorsque la divulgation de ces informations est requise par la loi, sur ordre d\u2019un tribunal ou toute autorit\u00e9 administrative ou judiciaire habilit\u00e9e \u00e0 en conna\u00eetre.<\/p>\n<h3>2.2. Configuration de vos pr\u00e9f\u00e9rences sur les cookies<\/h3>\n<p>Pour mieux vous \u00e9clairer sur les informations que les cookies identifient, vous trouverez ci-dessous la liste des diff\u00e9rents types de cookies susceptibles d\u2019\u00eatre utilis\u00e9s sur le site web de Lucibel.le Paris, leur nom, leur finalit\u00e9 ainsi que leur dur\u00e9e de conservation.<br>En cliquant sur \u00ab Configurer \u00bb sur le bandeau de bas de page vous pouvez accepter ou non l\u2019utilisation de certains cookies.<\/p>\n<p>a. Les cookies exempt\u00e9s de consentement<\/p>\n<p>Conform\u00e9ment aux recommandations de la Commission Nationale de l\u2019Informatique et des Libert\u00e9s (CNIL), certains cookies sont dispens\u00e9s du recueil pr\u00e9alable de votre consentement dans la mesure o\u00f9 ils sont strictement n\u00e9cessaires au fonctionnement du site internet ou ont pour finalit\u00e9 exclusive de permettre ou faciliter la communication par voie \u00e9lectronique.<\/p>\n<p>Il s\u2019agit notamment des cookies d\u2019identifiant de session, d\u2019authentification, de session d\u2019\u00e9quilibrage de charge ainsi que des cookies de personnalisation de votre interface. Ces cookies sont int\u00e9gralement soumis \u00e0 la pr\u00e9sente politique dans la mesure o\u00f9 ils sont \u00e9mis et g\u00e9r\u00e9s par Lucibel.le Paris.<\/p>\n<p>Le site internet lucibelleparis.com utilise des cookies (traceurs). Ce sont de petits fichiers informatiques d\u00e9pos\u00e9s sur votre terminal lors de votre visite sur le site. La plupart des cookies utilis\u00e9s sur ce site web sont n\u00e9cessaires \u00e0 la navigation et au bon affichage du pr\u00e9sent site, tandis que quelques autres recueillent des statistiques de visites anonymes.<\/p>\n<p>Des cookies ont pour finalit\u00e9s de permettre une navigation et un affichage des pages optimaux sur notre site ainsi que de contr\u00f4ler le respect de la vie priv\u00e9e des utilisateurs. L\u2019utilisation de ces traceurs ne requiert pas votre consentement selon l\u2019article 32 II de la loi n\u00b0 78-17 du 6 janvier 1978.<\/p>\n<p>Nom du cookie Finalit\u00e9 du cookie<br>PHPSESSID Cookie de stockage des donn\u00e9es de navigation permettant le passage d\u2019une page \u00e0 l\u2019autre sans perte d\u2019information. Il ne sert qu\u2019au bon fonctionnement du site.<br>wfwaf-authcookie Cookie de protection du site. Il ne sert qu\u2019au bon fonctionnement du site.<\/p>\n<p>b. Les cookies n\u00e9cessitant le recueil pr\u00e9alable de votre consentement<\/p>\n<p>Cette exigence concerne les cookies \u00e9mis par des tiers et qui sont qualifi\u00e9s de \u00ab persistants \u00bb dans la mesure o\u00f9 ils demeurent dans votre terminal jusqu\u2019\u00e0 leur effacement ou leur date d\u2019expiration. De tels cookies \u00e9tant \u00e9mis par des tiers, leur utilisation et leur d\u00e9p\u00f4t sont soumis \u00e0 leurs propres politiques de confidentialit\u00e9 dont vous trouverez un lien ci-dessous. Cette famille de cookie regroupe les cookies publicitaires (auxquels Lucibel.le Paris n\u2019a pas recours) ainsi que les cookies de partage de r\u00e9seaux sociaux (notamment de Facebook, Pinterest, Twitter et Google Plus). Les cookies de partage des r\u00e9seaux sociaux sont \u00e9mis et g\u00e9r\u00e9s par l\u2019\u00e9diteur du r\u00e9seau social concern\u00e9.<\/p>\n<p>Sous r\u00e9serve de votre consentement, ces cookies vous permettent de partager facilement une partie du contenu publi\u00e9 sur le site de Lucibel.le Paris, notamment par l\u2019interm\u00e9diaire d\u2019un \u00ab bouton \u00bb applicatif de partage selon le r\u00e9seau social concern\u00e9. Quatre types de cookies de partage des r\u00e9seaux sociaux sont pr\u00e9sents sur le site de Lucibel.le Paris :<\/p>\n<p>Facebook, dont vous pouvez consulter la politique en mati\u00e8re de cookies en cliquant sur le lien suivant : https:\/\/fr-fr.facebook.com\/policies\/cookies\/<br>Pinterest, dont vous pouvez consulter la politique en mati\u00e8re de cookies en cliquant sur le lien suivant : https:\/\/policy.pinterest.com\/fr\/cookies<br>Google Plus, dont vous trouverez la politique relative aux cookies en cliquant sur le lien suivant : https:\/\/policies.google.com\/technologies\/cookies?hl=fr<br>Vous trouverez l\u2019aide n\u00e9cessaire pour supprimer les cookies \u00e0 partir du navigateur Google Chrome en cliquant sur le lien suivant : https:\/\/support.google.com\/youtube\/answer\/32050?hl=fr mais \u00e9galement la politique compl\u00e8te en mati\u00e8re de cookies \u00e0 partir du lien suivant : https:\/\/www.google.fr\/intl\/fr\/policies\/technologies\/cookies\/<br>Twitter, dont vous trouverez les options d\u00e9di\u00e9es au contr\u00f4le ou \u00e0 la restriction de l\u2019utilisation des cookies ainsi que la politique d\u2019utilisation des cookies : https:\/\/support.twitter.com\/articles\/20170518#<\/p>\n<p>Nom du cookie Finalit\u00e9 du cookie<br>moove_gdpr_popup Cookie d\u2019aide \u00e0 la conformit\u00e9 au R\u00e8glement europ\u00e9en sur la protection des donn\u00e9es (RGPD).<br>gdprcompliance Cookie de gestion des tags. Il permet le contr\u00f4le de l\u2019utilisateur du consentement \u00e0 voir ses donn\u00e9es anonymes de visite r\u00e9utilis\u00e9es par le responsable du site.<br>gdpr[consent_types] Cookie d\u2019aide \u00e0 la conformit\u00e9 au R\u00e8glement europ\u00e9en sur la protection des donn\u00e9es (RGPD).<br>gdpr[allowed_cookies] Cookie d\u2019aide \u00e0 la conformit\u00e9 au R\u00e8glement europ\u00e9en sur la protection des donn\u00e9es (RGPD).<br>_ga, _gat_gtag, _gid Cookies de Google Analytics recueillant des statistiques de visites anonymes pour am\u00e9liorer l\u2019accessibilit\u00e9 des contenus, la navigation et l\u2019exp\u00e9rience utilisateur sur le site. Potentiellement intrusif pour votre vie priv\u00e9e, le d\u00e9p\u00f4t de ces cookies n\u00e9cessite votre consentement.<\/p>\n<p>c. Vous disposez de divers outils de param\u00e9trage des cookies<\/p>\n<p>La plupart des navigateurs Internet sont configur\u00e9s par d\u00e9faut de fa\u00e7on \u00e0 ce que le d\u00e9p\u00f4t de cookies soit autoris\u00e9. en plus de l\u2019outil de gestion des cookies que nous avons mis en place sur notre site, votre navigateur vous offre l\u2019opportunit\u00e9 de modifier ces param\u00e8tres standards de mani\u00e8re \u00e0 ce que l\u2019ensemble des cookies soit rejet\u00e9 syst\u00e9matiquement ou bien \u00e0 ce qu\u2019une partie seulement des cookies soit accept\u00e9e ou refus\u00e9e en fonction de leur \u00e9metteur.<br>ATTENTION : Nous attirons votre attention sur le fait que le refus du d\u00e9p\u00f4t de cookies sur votre terminal est n\u00e9anmoins susceptible d\u2019alt\u00e9rer votre exp\u00e9rience d\u2019utilisateur ainsi que votre acc\u00e8s \u00e0 certains services ou fonctionnalit\u00e9s du pr\u00e9sent site web. Le cas \u00e9ch\u00e9ant, Lucibel.le Paris d\u00e9cline toute responsabilit\u00e9 concernant les cons\u00e9quences li\u00e9es \u00e0 la d\u00e9gradation de vos conditions de navigation qui interviennent en raison de votre choix de refuser, supprimer ou bloquer les cookies n\u00e9cessaires au fonctionnement du site. Ces cons\u00e9quences ne sauraient constituer un dommage et vous ne pourrez pr\u00e9tendre \u00e0 aucune indemnit\u00e9 de ce fait. Votre navigateur vous permet \u00e9galement de supprimer les cookies existants sur votre terminal ou encore de vous signaler lorsque de nouveaux cookies sont susceptibles d\u2019\u00eatre d\u00e9pos\u00e9s sur votre terminal. Ces param\u00e9trages n\u2019ont pas d\u2019incidence sur votre navigation mais vous font perdre tout le b\u00e9n\u00e9fice apport\u00e9 par le cookie. Veuillez ci-dessous prendre connaissance des multiples outils mis \u00e0 votre disposition afin que vous puissiez param\u00e9trer les cookies d\u00e9pos\u00e9s sur votre terminal.<br>d. Le param\u00e9trage de votre navigateur Internet<br>Chaque navigateur Internet propose ses propres param\u00e8tres de gestion des cookies. Pour savoir de quelle mani\u00e8re modifier vos pr\u00e9f\u00e9rences en mati\u00e8re de cookies, vous trouverez ci-dessous les liens vers l\u2019aide n\u00e9cessaire pour acc\u00e9der au menu de votre navigateur pr\u00e9vu \u00e0 cet effet :<br>Chrome : https:\/\/support.google.com\/chrome\/answer\/95647?hl=fr<br>Firefox : https:\/\/support.mozilla.org\/fr\/kb\/activer-desactiver-cookies<br>Internet Explorer : https:\/\/support.microsoft.com\/fr-fr\/help\/17442\/windows-internet-explorer-delete-manage-cookies#ie=ie-11<br>Opera : http:\/\/help.opera.com\/Windows\/10.20\/fr\/cookies.html<br>Safari : https:\/\/support.apple.com\/kb\/PH21411?viewlocale=fr_FR&amp;locale=fr_FR<br>Pour de plus amples informations concernant les outils de ma\u00eetrise des cookies, vous pouvez consulter le site internet de la CNIL : https:\/\/www.cnil.fr\/fr\/cookies-les-outils-pour-les-maitriser.<br>A moins qu\u2019un consentement expr\u00e8s ne soit requis par les lois de votre pays en mati\u00e8re de protection des donn\u00e9es personnelles, en utilisant les pr\u00e9sents Supports (tels qu\u2019ils sont d\u00e9finis ci-dessus), vous consentez \u00e0 ce que nous collections et utilisions vos donn\u00e9es personnelles de la mani\u00e8re d\u00e9crite dans la pr\u00e9sente Politique et au transfert de vos donn\u00e9es personnelles vers d\u2019autres pays que le v\u00f4tre (y compris vers des pays situ\u00e9s en dehors de l\u2019Union Europ\u00e9enne).<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Politique de confidentialit\u00e9 Lucibel.le Paris a pour ambition d\u2019\u00eatre une entreprise citoyenne exemplaire et de contribuer \u00e0 la cr\u00e9ation d\u2019un monde \u00e9l\u00e9gant. Nous accordons une grande valeur \u00e0 l\u2019honn\u00eatet\u00e9 et \u00e0 la clart\u00e9 et avons \u00e0 c\u0153ur de construire avec nos clients des relations fortes et durables, fond\u00e9es sur la confiance et l\u2019int\u00e9r\u00eat mutuel. Conform\u00e9ment [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-5075","page","type-page","status-publish","hentry"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Politique de confidentialit\u00e9 Lucibel.le Paris a pour ambition d\u2019\u00eatre une entreprise citoyenne exemplaire et de contribuer \u00e0 la cr\u00e9ation d\u2019un monde \u00e9l\u00e9gant. Nous accordons une grande valeur \u00e0 l\u2019honn\u00eatet\u00e9 et \u00e0 la clart\u00e9 et avons \u00e0 c\u0153ur de construire avec nos clients des relations fortes et durables, fond\u00e9es sur la confiance et l\u2019int\u00e9r\u00eat mutuel. Conform\u00e9ment\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/lucibelleparis.com\/en\/politique-de-confidentialite\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Lucibel\u00b7le Paris - Le pouvoir de la Lumi\u00e8re\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Politique de confidentialit\u00e9 - Lucibel\u00b7le Paris\" \/>\n\t\t<meta property=\"og:description\" content=\"Politique de confidentialit\u00e9 Lucibel.le Paris a pour ambition d\u2019\u00eatre une entreprise citoyenne exemplaire et de contribuer \u00e0 la cr\u00e9ation d\u2019un monde \u00e9l\u00e9gant. Nous accordons une grande valeur \u00e0 l\u2019honn\u00eatet\u00e9 et \u00e0 la clart\u00e9 et avons \u00e0 c\u0153ur de construire avec nos clients des relations fortes et durables, fond\u00e9es sur la confiance et l\u2019int\u00e9r\u00eat mutuel. Conform\u00e9ment\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/lucibelleparis.com\/en\/politique-de-confidentialite\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/lucibelleparis.com\/wp-content\/uploads\/2024\/11\/lucibelle-logo.svg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/lucibelleparis.com\/wp-content\/uploads\/2024\/11\/lucibelle-logo.svg\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2023-02-16T07:42:34+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-06-18T10:58:04+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Politique de confidentialit\u00e9 - Lucibel\u00b7le Paris\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Politique de confidentialit\u00e9 Lucibel.le Paris a pour ambition d\u2019\u00eatre une entreprise citoyenne exemplaire et de contribuer \u00e0 la cr\u00e9ation d\u2019un monde \u00e9l\u00e9gant. Nous accordons une grande valeur \u00e0 l\u2019honn\u00eatet\u00e9 et \u00e0 la clart\u00e9 et avons \u00e0 c\u0153ur de construire avec nos clients des relations fortes et durables, fond\u00e9es sur la confiance et l\u2019int\u00e9r\u00eat mutuel. Conform\u00e9ment\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/lucibelleparis.com\/wp-content\/uploads\/2024\/11\/lucibelle-logo.svg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lucibelleparis.com\\\/en\\\/politique-de-confidentialite\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/lucibelleparis.com\\\/en\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/lucibelleparis.com\\\/en\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/lucibelleparis.com\\\/en\\\/politique-de-confidentialite\\\/#listItem\",\"name\":\"Politique de confidentialit\\u00e9\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/lucibelleparis.com\\\/en\\\/politique-de-confidentialite\\\/#listItem\",\"position\":2,\"name\":\"Politique de confidentialit\\u00e9\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/lucibelleparis.com\\\/en\\\/#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lucibelleparis.com\\\/en\\\/#organization\",\"name\":\"Lucibel\\u00b7le Paris\",\"description\":\"Le pouvoir de la Lumi\\u00e8re Le pouvoir de la lumi\\u00e8re\",\"url\":\"https:\\\/\\\/lucibelleparis.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/lucibelleparis.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/lucibelle-logo.svg\",\"@id\":\"https:\\\/\\\/lucibelleparis.com\\\/en\\\/politique-de-confidentialite\\\/#organizationLogo\",\"width\":126,\"height\":34},\"image\":{\"@id\":\"https:\\\/\\\/lucibelleparis.com\\\/en\\\/politique-de-confidentialite\\\/#organizationLogo\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lucibelleparis.com\\\/en\\\/politique-de-confidentialite\\\/#webpage\",\"url\":\"https:\\\/\\\/lucibelleparis.com\\\/en\\\/politique-de-confidentialite\\\/\",\"name\":\"Politique de confidentialit\\u00e9 - Lucibel\\u00b7le Paris\",\"description\":\"Politique de confidentialit\\u00e9 Lucibel.le Paris a pour ambition d\\u2019\\u00eatre une entreprise citoyenne exemplaire et de contribuer \\u00e0 la cr\\u00e9ation d\\u2019un monde \\u00e9l\\u00e9gant. Nous accordons une grande valeur \\u00e0 l\\u2019honn\\u00eatet\\u00e9 et \\u00e0 la clart\\u00e9 et avons \\u00e0 c\\u0153ur de construire avec nos clients des relations fortes et durables, fond\\u00e9es sur la confiance et l\\u2019int\\u00e9r\\u00eat mutuel. Conform\\u00e9ment\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lucibelleparis.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lucibelleparis.com\\\/en\\\/politique-de-confidentialite\\\/#breadcrumblist\"},\"datePublished\":\"2023-02-16T08:42:34+01:00\",\"dateModified\":\"2026-06-18T11:58:04+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lucibelleparis.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/lucibelleparis.com\\\/en\\\/\",\"name\":\"Lucibel\\u00b7le Paris\",\"description\":\"Le pouvoir de la Lumi\\u00e8re\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/lucibelleparis.com\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Politique de confidentialit\u00e9 - Lucibel\u00b7le Paris","description":"Politique de confidentialit\u00e9 Lucibel.le Paris a pour ambition d\u2019\u00eatre une entreprise citoyenne exemplaire et de contribuer \u00e0 la cr\u00e9ation d\u2019un monde \u00e9l\u00e9gant. Nous accordons une grande valeur \u00e0 l\u2019honn\u00eatet\u00e9 et \u00e0 la clart\u00e9 et avons \u00e0 c\u0153ur de construire avec nos clients des relations fortes et durables, fond\u00e9es sur la confiance et l\u2019int\u00e9r\u00eat mutuel. Conform\u00e9ment","canonical_url":"https:\/\/lucibelleparis.com\/en\/politique-de-confidentialite\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/lucibelleparis.com\/en\/politique-de-confidentialite\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/lucibelleparis.com\/en\/#listItem","position":1,"name":"Home","item":"https:\/\/lucibelleparis.com\/en\/","nextItem":{"@type":"ListItem","@id":"https:\/\/lucibelleparis.com\/en\/politique-de-confidentialite\/#listItem","name":"Politique de confidentialit\u00e9"}},{"@type":"ListItem","@id":"https:\/\/lucibelleparis.com\/en\/politique-de-confidentialite\/#listItem","position":2,"name":"Politique de confidentialit\u00e9","previousItem":{"@type":"ListItem","@id":"https:\/\/lucibelleparis.com\/en\/#listItem","name":"Home"}}]},{"@type":"Organization","@id":"https:\/\/lucibelleparis.com\/en\/#organization","name":"Lucibel\u00b7le Paris","description":"Le pouvoir de la Lumi\u00e8re Le pouvoir de la lumi\u00e8re","url":"https:\/\/lucibelleparis.com\/en\/","logo":{"@type":"ImageObject","url":"https:\/\/lucibelleparis.com\/wp-content\/uploads\/2024\/11\/lucibelle-logo.svg","@id":"https:\/\/lucibelleparis.com\/en\/politique-de-confidentialite\/#organizationLogo","width":126,"height":34},"image":{"@id":"https:\/\/lucibelleparis.com\/en\/politique-de-confidentialite\/#organizationLogo"}},{"@type":"WebPage","@id":"https:\/\/lucibelleparis.com\/en\/politique-de-confidentialite\/#webpage","url":"https:\/\/lucibelleparis.com\/en\/politique-de-confidentialite\/","name":"Politique de confidentialit\u00e9 - Lucibel\u00b7le Paris","description":"Politique de confidentialit\u00e9 Lucibel.le Paris a pour ambition d\u2019\u00eatre une entreprise citoyenne exemplaire et de contribuer \u00e0 la cr\u00e9ation d\u2019un monde \u00e9l\u00e9gant. Nous accordons une grande valeur \u00e0 l\u2019honn\u00eatet\u00e9 et \u00e0 la clart\u00e9 et avons \u00e0 c\u0153ur de construire avec nos clients des relations fortes et durables, fond\u00e9es sur la confiance et l\u2019int\u00e9r\u00eat mutuel. Conform\u00e9ment","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/lucibelleparis.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/lucibelleparis.com\/en\/politique-de-confidentialite\/#breadcrumblist"},"datePublished":"2023-02-16T08:42:34+01:00","dateModified":"2026-06-18T11:58:04+01:00"},{"@type":"WebSite","@id":"https:\/\/lucibelleparis.com\/en\/#website","url":"https:\/\/lucibelleparis.com\/en\/","name":"Lucibel\u00b7le Paris","description":"Le pouvoir de la Lumi\u00e8re","inLanguage":"en-US","publisher":{"@id":"https:\/\/lucibelleparis.com\/en\/#organization"}}]},"og:locale":"en_US","og:site_name":"Lucibel\u00b7le Paris - Le pouvoir de la Lumi\u00e8re","og:type":"article","og:title":"Politique de confidentialit\u00e9 - Lucibel\u00b7le Paris","og:description":"Politique de confidentialit\u00e9 Lucibel.le Paris a pour ambition d\u2019\u00eatre une entreprise citoyenne exemplaire et de contribuer \u00e0 la cr\u00e9ation d\u2019un monde \u00e9l\u00e9gant. Nous accordons une grande valeur \u00e0 l\u2019honn\u00eatet\u00e9 et \u00e0 la clart\u00e9 et avons \u00e0 c\u0153ur de construire avec nos clients des relations fortes et durables, fond\u00e9es sur la confiance et l\u2019int\u00e9r\u00eat mutuel. Conform\u00e9ment","og:url":"https:\/\/lucibelleparis.com\/en\/politique-de-confidentialite\/","og:image":"https:\/\/lucibelleparis.com\/wp-content\/uploads\/2024\/11\/lucibelle-logo.svg","og:image:secure_url":"https:\/\/lucibelleparis.com\/wp-content\/uploads\/2024\/11\/lucibelle-logo.svg","article:published_time":"2023-02-16T07:42:34+00:00","article:modified_time":"2026-06-18T10:58:04+00:00","twitter:card":"summary_large_image","twitter:title":"Politique de confidentialit\u00e9 - Lucibel\u00b7le Paris","twitter:description":"Politique de confidentialit\u00e9 Lucibel.le Paris a pour ambition d\u2019\u00eatre une entreprise citoyenne exemplaire et de contribuer \u00e0 la cr\u00e9ation d\u2019un monde \u00e9l\u00e9gant. Nous accordons une grande valeur \u00e0 l\u2019honn\u00eatet\u00e9 et \u00e0 la clart\u00e9 et avons \u00e0 c\u0153ur de construire avec nos clients des relations fortes et durables, fond\u00e9es sur la confiance et l\u2019int\u00e9r\u00eat mutuel. Conform\u00e9ment","twitter:image":"https:\/\/lucibelleparis.com\/wp-content\/uploads\/2024\/11\/lucibelle-logo.svg"},"aioseo_meta_data":{"post_id":"5075","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2024-08-05 13:27:50","updated":"2026-06-18 11:16:14","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/lucibelleparis.com\/en\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tPolitique de confidentialit\u00e9\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/lucibelleparis.com\/en\/"},{"label":"Politique de confidentialit\u00e9","link":"https:\/\/lucibelleparis.com\/en\/politique-de-confidentialite\/"}],"_links":{"self":[{"href":"https:\/\/lucibelleparis.com\/en\/wp-json\/wp\/v2\/pages\/5075","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lucibelleparis.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/lucibelleparis.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/lucibelleparis.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/lucibelleparis.com\/en\/wp-json\/wp\/v2\/comments?post=5075"}],"version-history":[{"count":18,"href":"https:\/\/lucibelleparis.com\/en\/wp-json\/wp\/v2\/pages\/5075\/revisions"}],"predecessor-version":[{"id":16412,"href":"https:\/\/lucibelleparis.com\/en\/wp-json\/wp\/v2\/pages\/5075\/revisions\/16412"}],"wp:attachment":[{"href":"https:\/\/lucibelleparis.com\/en\/wp-json\/wp\/v2\/media?parent=5075"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}